{"id":3898,"date":"2025-12-13T05:59:42","date_gmt":"2025-12-13T04:59:42","guid":{"rendered":"https:\/\/www.lern-verlag.de\/blog\/?p=3898"},"modified":"2025-02-11T11:00:44","modified_gmt":"2025-02-11T10:00:44","slug":"abi-trainer-2026-fos-13-ibv","status":"publish","type":"post","link":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/","title":{"rendered":"Abi-Trainer 2026 FOS 13 IBV"},"content":{"rendered":"<p>Abi-Trainer 2026 FOS 13 IBV. Die Abi Vorbereitung 2026 bei den Lehrbuch-Profis ist eine optimale Wahl, wenn es um ein erfolgreiches Abi 2026 geht.\u00a0 Der Abi-Trainer 2025 f\u00fcr die Berufliche Oberschule aus dem Hause <a href=\"https:\/\/www.lern-verlag.de\">lernverlag<\/a>, ist der passende Wegbegleiter schon w\u00e4hrend des Schuljahres. Er dient als gute Vorbereitung auf den kommenden Leistungsnachweis und ist ideal f\u00fcr alle Fachobersch\u00fcler. Abi-Trainer 2026 FOS 13 IBV mit vielen kostenlosen \u00dcbungsaufgaben bereitet zielgerichtet auf die kommende Kurzarbeit oder Schulaufgabe in IBV an Beruflichen Oberschulen, mithilfe der Pr\u00fcfungen aus den vergangenen Jahren, vor. Die L\u00f6sungen sind ausf\u00fchrlich und nachvollziehbar verfasst und speziell f\u00fcr schw\u00e4chere Sch\u00fcler geschrieben. Nat\u00fcrlich ist die Original-Pr\u00fcfung 2026 mit L\u00f6sungen mit abgedruckt.<br \/>\nIn jedem Trainer f\u00fcr die FOS\/BOS in Bayern finden Sie die Original Pr\u00fcfungen, sortiert nach den einzelnen Jahrg\u00e4ngen.<\/p>\n<p><strong>Abi-Trainer 2026 FOS 13 IBV sichern &#8211; Notenbesserung<\/strong><\/p>\n<p>Der \u201c<a href=\"https:\/\/www.lern-verlag.de\/Pruefungsvorbereitung\/Bayern\/Berufliche-Oberschule\/\">ABi-Trainer IBV 13<\/a>\u201d mit den Pr\u00fcfungen der letzten Jahre bereitet ausf\u00fchrlich auf das Abitur und auf die Schulaufgaben w\u00e4hrend des Schuljahres vor, da diese Lernhilfe ausf\u00fchrliche L\u00f6sungen zu den Original-Pr\u00fcfungen, die so auch von engagierten Lehrkr\u00e4ften im Unterricht erstellt worden sind, beinhaltet.<br \/>\nDaher ist er eine gute M\u00f6glichkeit zur Notenbesserung und aber auch zur Pr\u00fcfungsvorbereitung auf das Abi FOS\/BOS in Bayern.<\/p>\n<h2>Abi-Trainer 2026 FOS 13 IBV<\/h2>\n<p>Mit Hilfe der vielen kostenlos abgedruckten \u00dcbungen, ist das der ideale Band um sich gr\u00fcndlich auf die Abschlusspr\u00fcfung in IBV in Bayern vorzubereiten.<br \/>\nZudem gibt es<\/p>\n<ul>\n<li>nach jeder Aufgabengruppe die entsprechende, ausf\u00fchrliche, nachvollziehbare L\u00f6sung,<\/li>\n<li>ein Miniskript mit einem \u00dcbungsteil, da so auch w\u00e4hrend des Schuljahres die Vorbereitung auf einzelne Pr\u00fcfungen m\u00f6glich ist und<\/li>\n<li>L\u00f6sungen zu den einzelnen Pr\u00fcfungsaufgaben, die auch dem Unterricht in der Schule entsprechen.<\/li>\n<\/ul>\n<p>Alle L\u00f6sungen sind vollst\u00e4ndig, ausf\u00fchrlich, nachvollziehbar und sch\u00fclergerecht geschrieben. Deshalb ist das ideal um sich auf die Schulaufgaben oder Kurzarbeiten vorzubereiten oder Karteikarten zum Lernen zu erstellen.<\/p>\n<p><strong>Alle FOS-Kurse 2026 auf einen Blick<\/strong><\/p>\n<p>Wollen Sie eine gute, kosteng\u00fcnstige und effektive Abi-Vorbereitung kurz vor den Pr\u00fcfungen, dann schauen Sie sich unsere 2026 Kurse an.<br \/>\n<a href=\"https:\/\/lern.de\/fos-bos\/\">Hier klicken!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jetzt Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4<\/p>\n","protected":false},"author":1,"featured_media":3321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[620,618,8,560,6,619,621,566,5,738,132,23,739,737,2,740,491,477,478],"class_list":["post-3898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fos-bos","tag-abiturpruefung","tag-allgemeine-hochschulreife","tag-berufliche-oberschule","tag-berufsoberschule","tag-bos","tag-fachabiturpruefung","tag-fachgebundene-hochschulreife","tag-fachoberschule","tag-fos","tag-fos-13-ibv","tag-fos-ibv","tag-ibv","tag-internationale-betriebswirtschaftslehre","tag-internationale-volkswirtschaftslehre","tag-lehrplanplus","tag-lernhilfe","tag-uebungen","tag-wiederholen","tag-zentrale-pruefung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abi-Trainer 2026 FOS 13 IBV - lernverlag Blog<\/title>\n<meta name=\"description\" content=\"Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abi-Trainer 2026 FOS 13 IBV - lernverlag Blog\" \/>\n<meta property=\"og:description\" content=\"Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/\" \/>\n<meta property=\"og:site_name\" content=\"lernverlag Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lernverlag\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-13T04:59:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2025\/02\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lernverlag Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lernverlag\" \/>\n<meta name=\"twitter:site\" content=\"@lernverlag\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lernverlag Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/\"},\"author\":{\"name\":\"lernverlag Team\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#\\\/schema\\\/person\\\/d6df3778b4bc053f1b3738b6e928d505\"},\"headline\":\"Abi-Trainer 2026 FOS 13 IBV\",\"datePublished\":\"2025-12-13T04:59:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/\"},\"wordCount\":354,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg\",\"keywords\":[\"Abiturpr\u00fcfung\",\"Allgemeine Hochschulreife\",\"Berufliche Oberschule\",\"Berufsoberschule\",\"BOS\",\"Fachabiturpr\u00fcfung\",\"Fachgebundene Hochschulreife\",\"Fachoberschule\",\"FOS\",\"FOS 13 IBV\",\"FOS IBV\",\"IBV\",\"Internationale Betriebswirtschaftslehre\",\"Internationale Volkswirtschaftslehre\",\"LehrplanPLUS\",\"Lernhilfe\",\"\u00dcbungen\",\"Wiederholen\",\"Zentrale Pr\u00fcfung\"],\"articleSection\":[\"Berufliche Oberschule\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/\",\"name\":\"Abi-Trainer 2026 FOS 13 IBV - lernverlag Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg\",\"datePublished\":\"2025-12-13T04:59:42+00:00\",\"description\":\"Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"FOSBOS13 2026 Abitur Bayern IBV. ISBN 978-3-7430-0137-4\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/2025\\\/12\\\/13\\\/abi-trainer-2026-fos-13-ibv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abi-Trainer 2026 FOS 13 IBV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/\",\"name\":\"lernverlag Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#organization\",\"name\":\"lernverlag der lern.de Bildungsgesellschaft mbH\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Logo_1200x630_Facebook_Post-e1540739613905.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Logo_1200x630_Facebook_Post-e1540739613905.jpg\",\"width\":800,\"height\":420,\"caption\":\"lernverlag der lern.de Bildungsgesellschaft mbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lernverlag\\\/\",\"https:\\\/\\\/x.com\\\/lernverlag\",\"https:\\\/\\\/www.instagram.com\\\/lernverlag\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/lernverlag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#\\\/schema\\\/person\\\/d6df3778b4bc053f1b3738b6e928d505\",\"name\":\"lernverlag Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741b5fa3c153bbad5c2922c2a211c3b45c95c70af34e36672eb3fa60c73e81e6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741b5fa3c153bbad5c2922c2a211c3b45c95c70af34e36672eb3fa60c73e81e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/741b5fa3c153bbad5c2922c2a211c3b45c95c70af34e36672eb3fa60c73e81e6?s=96&d=mm&r=g\",\"caption\":\"lernverlag Team\"},\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/author\\\/sascha\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abi-Trainer 2026 FOS 13 IBV - lernverlag Blog","description":"Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/","og_locale":"de_DE","og_type":"article","og_title":"Abi-Trainer 2026 FOS 13 IBV - lernverlag Blog","og_description":"Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4","og_url":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/","og_site_name":"lernverlag Blog","article_publisher":"https:\/\/www.facebook.com\/lernverlag\/","article_published_time":"2025-12-13T04:59:42+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2025\/02\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg","type":"image\/jpeg"}],"author":"lernverlag Team","twitter_card":"summary_large_image","twitter_creator":"@lernverlag","twitter_site":"@lernverlag","twitter_misc":{"Verfasst von":"lernverlag Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#article","isPartOf":{"@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/"},"author":{"name":"lernverlag Team","@id":"https:\/\/www.lern-verlag.de\/blog\/#\/schema\/person\/d6df3778b4bc053f1b3738b6e928d505"},"headline":"Abi-Trainer 2026 FOS 13 IBV","datePublished":"2025-12-13T04:59:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/"},"wordCount":354,"commentCount":0,"publisher":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2025\/02\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg","keywords":["Abiturpr\u00fcfung","Allgemeine Hochschulreife","Berufliche Oberschule","Berufsoberschule","BOS","Fachabiturpr\u00fcfung","Fachgebundene Hochschulreife","Fachoberschule","FOS","FOS 13 IBV","FOS IBV","IBV","Internationale Betriebswirtschaftslehre","Internationale Volkswirtschaftslehre","LehrplanPLUS","Lernhilfe","\u00dcbungen","Wiederholen","Zentrale Pr\u00fcfung"],"articleSection":["Berufliche Oberschule"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/","url":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/","name":"Abi-Trainer 2026 FOS 13 IBV - lernverlag Blog","isPartOf":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#primaryimage"},"image":{"@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2025\/02\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg","datePublished":"2025-12-13T04:59:42+00:00","description":"Abi-Trainer 2026 FOS 13 IBV sichern um sich optimal auf die kommende Abitur-Pr\u00fcfung in IBV vorzubereiten. ISBN 978-3-7430-0137-4","breadcrumb":{"@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#primaryimage","url":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2025\/02\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg","contentUrl":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2025\/02\/FOS13-IBV-2026_978-3-7430-0137-4_v1.jpg","width":1000,"height":1000,"caption":"FOSBOS13 2026 Abitur Bayern IBV. ISBN 978-3-7430-0137-4"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lern-verlag.de\/blog\/2025\/12\/13\/abi-trainer-2026-fos-13-ibv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lern-verlag.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Abi-Trainer 2026 FOS 13 IBV"}]},{"@type":"WebSite","@id":"https:\/\/www.lern-verlag.de\/blog\/#website","url":"https:\/\/www.lern-verlag.de\/blog\/","name":"lernverlag Blog","description":"","publisher":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lern-verlag.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lern-verlag.de\/blog\/#organization","name":"lernverlag der lern.de Bildungsgesellschaft mbH","url":"https:\/\/www.lern-verlag.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lern-verlag.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2018\/10\/Logo_1200x630_Facebook_Post-e1540739613905.jpg","contentUrl":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2018\/10\/Logo_1200x630_Facebook_Post-e1540739613905.jpg","width":800,"height":420,"caption":"lernverlag der lern.de Bildungsgesellschaft mbH"},"image":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lernverlag\/","https:\/\/x.com\/lernverlag","https:\/\/www.instagram.com\/lernverlag\/","https:\/\/www.pinterest.de\/lernverlag\/"]},{"@type":"Person","@id":"https:\/\/www.lern-verlag.de\/blog\/#\/schema\/person\/d6df3778b4bc053f1b3738b6e928d505","name":"lernverlag Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/741b5fa3c153bbad5c2922c2a211c3b45c95c70af34e36672eb3fa60c73e81e6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/741b5fa3c153bbad5c2922c2a211c3b45c95c70af34e36672eb3fa60c73e81e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/741b5fa3c153bbad5c2922c2a211c3b45c95c70af34e36672eb3fa60c73e81e6?s=96&d=mm&r=g","caption":"lernverlag Team"},"url":"https:\/\/www.lern-verlag.de\/blog\/author\/sascha\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":"1601bf569c2b441b8d5481f91cdfbf12","server":"vg09.met.vgwort.de","url":"https:\/\/vg09.met.vgwort.de\/na\/1601bf569c2b441b8d5481f91cdfbf12"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/posts\/3898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/comments?post=3898"}],"version-history":[{"count":1,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/posts\/3898\/revisions"}],"predecessor-version":[{"id":3899,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/posts\/3898\/revisions\/3899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/media\/3321"}],"wp:attachment":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/media?parent=3898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/categories?post=3898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/tags?post=3898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}