{"id":509,"count":344,"description":"","link":"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/","name":"Abschlusspr\u00fcfung","slug":"abschlusspruefung","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abschlusspr\u00fcfung Archive - lernverlag Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abschlusspr\u00fcfung Archive - lernverlag Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/\" \/>\n<meta property=\"og:site_name\" content=\"lernverlag Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2018\/10\/Logo_1200x630_Facebook_Post-e1540739613905.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@lernverlag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/tag\\\/abschlusspruefung\\\/\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/tag\\\/abschlusspruefung\\\/\",\"name\":\"Abschlusspr\u00fcfung Archive - lernverlag Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/tag\\\/abschlusspruefung\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/tag\\\/abschlusspruefung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abschlusspr\u00fcfung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/\",\"name\":\"lernverlag Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#organization\",\"name\":\"lernverlag der lern.de Bildungsgesellschaft mbH\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Logo_1200x630_Facebook_Post-e1540739613905.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Logo_1200x630_Facebook_Post-e1540739613905.jpg\",\"width\":800,\"height\":420,\"caption\":\"lernverlag der lern.de Bildungsgesellschaft mbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lern-verlag.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lernverlag\\\/\",\"https:\\\/\\\/x.com\\\/lernverlag\",\"https:\\\/\\\/www.instagram.com\\\/lernverlag\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/lernverlag\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abschlusspr\u00fcfung Archive - lernverlag Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Abschlusspr\u00fcfung Archive - lernverlag Blog","og_url":"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/","og_site_name":"lernverlag Blog","og_image":[{"width":800,"height":420,"url":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2018\/10\/Logo_1200x630_Facebook_Post-e1540739613905.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@lernverlag","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/","url":"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/","name":"Abschlusspr\u00fcfung Archive - lernverlag Blog","isPartOf":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lern-verlag.de\/blog\/tag\/abschlusspruefung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lern-verlag.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Abschlusspr\u00fcfung"}]},{"@type":"WebSite","@id":"https:\/\/www.lern-verlag.de\/blog\/#website","url":"https:\/\/www.lern-verlag.de\/blog\/","name":"lernverlag Blog","description":"","publisher":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lern-verlag.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.lern-verlag.de\/blog\/#organization","name":"lernverlag der lern.de Bildungsgesellschaft mbH","url":"https:\/\/www.lern-verlag.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lern-verlag.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2018\/10\/Logo_1200x630_Facebook_Post-e1540739613905.jpg","contentUrl":"https:\/\/www.lern-verlag.de\/blog\/wp-content\/uploads\/2018\/10\/Logo_1200x630_Facebook_Post-e1540739613905.jpg","width":800,"height":420,"caption":"lernverlag der lern.de Bildungsgesellschaft mbH"},"image":{"@id":"https:\/\/www.lern-verlag.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lernverlag\/","https:\/\/x.com\/lernverlag","https:\/\/www.instagram.com\/lernverlag\/","https:\/\/www.pinterest.de\/lernverlag\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/tags\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lern-verlag.de\/blog\/wp-json\/wp\/v2\/posts?tags=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}